{"id":346,"date":"2025-07-28T14:05:04","date_gmt":"2025-07-28T14:05:04","guid":{"rendered":"https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/?page_id=346"},"modified":"2025-09-04T09:42:05","modified_gmt":"2025-09-04T09:42:05","slug":"cosa-vedere","status":"publish","type":"page","link":"https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/cosa-vedere\/","title":{"rendered":"Cosa vedere"},"content":{"rendered":"\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\">Gubbio \u00e8 un gioiello incastonato nella verde Umbria e offre numerosi spunti turistici e culturali<\/h4>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"322\" src=\"https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/wp-content\/uploads\/2025\/07\/Senza-titolo-1-1024x322.png\" alt=\"\" class=\"wp-image-389\" srcset=\"https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/wp-content\/uploads\/2025\/07\/Senza-titolo-1-1024x322.png 1024w, https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/wp-content\/uploads\/2025\/07\/Senza-titolo-1-300x94.png 300w, https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/wp-content\/uploads\/2025\/07\/Senza-titolo-1-768x242.png 768w, https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/wp-content\/uploads\/2025\/07\/Senza-titolo-1-1536x484.png 1536w, https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/wp-content\/uploads\/2025\/07\/Senza-titolo-1-2048x645.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center has-large-font-size\">Luoghi da visitare<\/h4>\n\n\n\n<p class=\"has-text-align-center has-base-font-size\">La Basilica di Sant&#8217;Ubaldo<br>La piazza &#8220;sospesa&#8221; Piazza Grande<br>Palazzo dei Consoli e Palazzo Ducale<br>Palazzo del Bargello e Fontana dei Matti<br>Il Teatro Romano e il Parco Archeologico<br>Il Duomo e La Chiesa di San Francesco<br>La Funivia di Colle Eletto<br>La Gola del Bottaccione<br>L&#8217;Eremo di Fonte Avellana<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div style=\"height:52px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center\">Visita la pagina per maggiori informazioni<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/www.umbriatourism.it\/it\/gubbio\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"441\" height=\"245\" src=\"https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/wp-content\/uploads\/2025\/07\/logo-umbria-copia.png\" alt=\"\" class=\"wp-image-387\" style=\"width:250px\" srcset=\"https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/wp-content\/uploads\/2025\/07\/logo-umbria-copia.png 441w, https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/wp-content\/uploads\/2025\/07\/logo-umbria-copia-300x167.png 300w\" sizes=\"auto, (max-width: 441px) 100vw, 441px\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gubbio \u00e8 un gioiello incastonato nella verde Umbria e offre numerosi spunti turistici e culturali Luoghi da visitare La Basilica di Sant&#8217;UbaldoLa piazza &#8220;sospesa&#8221; Piazza GrandePalazzo dei Consoli e Palazzo DucalePalazzo del Bargello e Fontana dei MattiIl Teatro Romano e il Parco ArcheologicoIl Duomo e La Chiesa di San FrancescoLa Funivia di Colle ElettoLa Gola [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":9,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-346","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/wp-json\/wp\/v2\/pages\/346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/wp-json\/wp\/v2\/comments?post=346"}],"version-history":[{"count":10,"href":"https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/wp-json\/wp\/v2\/pages\/346\/revisions"}],"predecessor-version":[{"id":559,"href":"https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/wp-json\/wp\/v2\/pages\/346\/revisions\/559"}],"wp:attachment":[{"href":"https:\/\/www.arcierieugubini.it\/CoppaItaliaMaster2025\/wp-json\/wp\/v2\/media?parent=346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}